{"id":83,"date":"2008-09-26T18:00:35","date_gmt":"2008-09-26T16:00:35","guid":{"rendered":"http:\/\/www.stepponat.de\/blog\/?p=83"},"modified":"2025-12-27T15:37:59","modified_gmt":"2025-12-27T13:37:59","slug":"abbruch","status":"publish","type":"post","link":"https:\/\/www.stepponat.de\/blog\/archive\/83","title":{"rendered":"Abbruch?"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Eigentlich h\u00e4tte die \u00dcberschrift des heutigen Tages: &#8222;Tour de Cols&#8220; lauten sollen &#8211; den Col d&#8217;Izoard und den Col du Galibier hatten wir bei perfekten Wetterbedingungen bereits zur Mittagszeit hinter uns gelassen. Aber direkt danach ist Silkes Buell einfach stehen geblieben. Die Batterie wurde aufgrund eines defekten Reglers \u00fcberladen und sozusagen zum \u00dcberkochen gebracht. Ich habe mit meinem perfekten Verst\u00e4ndnis f\u00fcr die franz\u00f6sische Sprache erst einmal eine neue Batterie besorgt und jetzt warten wir darauf, dass diese mit dem allzeit griffbereiten Ladeger\u00e4t Ihre volle Kapazit\u00e4t erreicht. Morgen geht es dann im Notbetrieb hoffentlich zum n\u00e4chsten Buell H\u00e4ndler (mal sehen wie weit ein Mopped im Batteriebetrieb fahren kann&#8230;)<\/p>\n\n\n\n<p><br> Mit vieeel Gl\u00fcck kommen wir morgen beim Buell-H\u00e4ndler an und er hat die defekte Elektronik griffbereit. Wenn nicht, droht der Abbruch unserer Tour durch Frankreich.<br> Aber dazu morgen mehr an dieser Stelle&#8230;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"3687\" data-permalink=\"https:\/\/www.stepponat.de\/blog\/archive\/83\/image_055\" data-orig-file=\"https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_055.jpg?fit=1280%2C960&amp;ssl=1\" data-orig-size=\"1280,960\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Matthias Stepponat&quot;,&quot;camera&quot;:&quot;Xda orbit&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1222430152&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMAGE_055\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_055.jpg?fit=1024%2C768&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_055.jpg?resize=1024%2C768&#038;ssl=1\" alt=\"\" class=\"wp-image-3687\" srcset=\"https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_055.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_055.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_055.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<div class=\"postie-image-div\" style=\"padding-left: 30px;\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"3688\" data-permalink=\"https:\/\/www.stepponat.de\/blog\/archive\/83\/image_057\" data-orig-file=\"https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_057.jpg?fit=1280%2C960&amp;ssl=1\" data-orig-size=\"1280,960\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Matthias Stepponat&quot;,&quot;camera&quot;:&quot;Xda orbit&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1222444873&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMAGE_057\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_057.jpg?fit=1024%2C768&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_057.jpg?resize=1024%2C768&#038;ssl=1\" alt=\"\" class=\"wp-image-3688\" srcset=\"https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_057.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_057.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.stepponat.de\/wp-content\/uploads\/2008\/09\/IMAGE_057.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<div class=\"postie-image-div\" style=\"padding-left: 30px;\"><\/div>\n\n\n\n<p>[:]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eigentlich h\u00e4tte die \u00dcberschrift des heutigen Tages: &#8222;Tour de Cols&#8220; lauten sollen &#8211; den Col d&#8217;Izoard und den Col du Galibier hatten wir bei perfekten Wetterbedingungen bereits zur Mittagszeit hinter uns gelassen. Aber direkt danach ist Silkes Buell einfach stehen geblieben. Die Batterie wurde aufgrund eines defekten Reglers \u00fcberladen und sozusagen zum \u00dcberkochen gebracht. Ich [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[353,355],"class_list":["post-83","post","type-post","status-publish","format-standard","hentry","category-motorradtouren","tag-353","tag-alpen"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.stepponat.de\/blog\/archive\/author\/admin"},"uagb_comment_info":0,"uagb_excerpt":"Eigentlich h\u00e4tte die \u00dcberschrift des heutigen Tages: &#8222;Tour de Cols&#8220; lauten sollen &#8211; den Col d&#8217;Izoard und den Col du Galibier hatten wir bei perfekten Wetterbedingungen bereits zur Mittagszeit hinter uns gelassen. Aber direkt danach ist Silkes Buell einfach stehen geblieben. Die Batterie wurde aufgrund eines defekten Reglers \u00fcberladen und sozusagen zum \u00dcberkochen gebracht. Ich&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s3AlH9-abbruch","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/posts\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":2,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"predecessor-version":[{"id":3690,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/posts\/83\/revisions\/3690"}],"wp:attachment":[{"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/tags?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}