{"id":836,"date":"2014-11-24T19:50:30","date_gmt":"2014-11-24T17:50:30","guid":{"rendered":"http:\/\/www.stepponat.de\/blog\/?p=836"},"modified":"2025-12-28T11:32:33","modified_gmt":"2025-12-28T09:32:33","slug":"ruhetage-und-ganz-viel-wasser","status":"publish","type":"post","link":"https:\/\/www.stepponat.de\/blog\/archive\/836","title":{"rendered":"Ruhetage und ganz viel Wasser"},"content":{"rendered":"\n<p>Die R\u00fcckreise hat so langsam angefangen. Iguacu war auf alle F\u00e4lle eine Reise wert. Die Wasserf\u00e4lle sind gigantisch &#8211; der Tourismus auch. Wir sind nat\u00fcrlich auch gute Touristen und haben zun\u00e4chst mit dem Speeboot die Wasserf\u00e4lle von unten begutachtet &#8211; man k\u00f6nnte auch sagen wir haben die Wasserf\u00e4lle aus n\u00e4chster N\u00e4he Hautnah erleben d\u00fcrfen. Danach sind wir auf der Brasilianischen Seite an den F\u00e4llen lang gewandert. Der Aussichtsweg ist auf der brasilianischen Seite ca. 1,5km lang und man kann dort die F\u00e4lle in der ganzen Pracht bewundern. Auch kann man die Touris sehen, die sich leichtsinnigerweise mit dem Boot n\u00e4hern und dabei bis auf die Knochen nass werden. Gl\u00fccklicherweise wird man hier auch bei entsprechenden Temperaturen auch schnell wieder trocken.<br> Um den Tag ausklingen zu lassen, g\u00f6nnen wir uns dann auch noch einen Rundflug mit dem Helikopter \u00fcber den Foz do Iguacu. Die Bilder dieser Tour werden folgen, sobald ich wieder zu Hause bin. Daf\u00fcr, dass wir kein Mopped gefahren sind, war das mal echt ein extrem guter Tag.<\/p>\n\n\n\n<p>Am Sonntag machen wir uns dann auf die R\u00fcckreise &#8211; allerdings g\u00f6nnen  wir uns noch eine Stunde um den Vogelpark zu besichtigen. Wer hier in der Gegend ist, sollte sich unbedingt die Zeit nehmen sich das anzusehen.<\/p>\n\n\n\n<p>Der R\u00fcckweg f\u00fchrt uns wieder durch die rot-gr\u00fcne Argentinische H\u00f6lle zur\u00fcck nach Brasilien. Die Tagestour liegt bei ca. 360km mit ca. 33 Grad Celcius. Am Ende des Tages sind alle fertig und sp\u00e4testens die letzten Zwei Stunden der Tour kann niemand mehr genie\u00dfen.<\/p>\n\n\n\n<p>Daf\u00fcr ging es dann am Montag mit einer sehr kurzen Tour von ca. 170km weiter nach Aberlardo Luz. Bis auf eine kurze Passage von 15km ist alles asphaltiert. Das laute Schreien der Stollreifen hat sich mittlerweile zu einem leisen Summen gewandelt &#8211; ist schon fast wie ein echter Stra\u00dfenreifen. Wir kommen schon gegen 13 Uhr im Hotel an und k\u00f6nnen die Aussicht genie\u00dfen. Au\u00dferdem hilft es bei einem Buch oder Kaltgetr\u00e4nk am Pool die Akkus aufzuladen w\u00e4hrend Mauricio uns hinten neue Stollenreifen aufzieht.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die R\u00fcckreise hat so langsam angefangen. Iguacu war auf alle F\u00e4lle eine Reise wert. Die Wasserf\u00e4lle sind gigantisch &#8211; der Tourismus auch. Wir sind nat\u00fcrlich auch gute Touristen und haben zun\u00e4chst mit dem Speeboot die Wasserf\u00e4lle von unten begutachtet &#8211; man k\u00f6nnte auch sagen wir haben die Wasserf\u00e4lle aus n\u00e4chster N\u00e4he Hautnah erleben d\u00fcrfen. Danach [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[25],"tags":[],"class_list":["post-836","post","type-post","status-publish","format-standard","hentry","category-brasilien"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Matthias","author_link":"https:\/\/www.stepponat.de\/blog\/archive\/author\/matthias"},"uagb_comment_info":0,"uagb_excerpt":"Die R\u00fcckreise hat so langsam angefangen. Iguacu war auf alle F\u00e4lle eine Reise wert. Die Wasserf\u00e4lle sind gigantisch &#8211; der Tourismus auch. Wir sind nat\u00fcrlich auch gute Touristen und haben zun\u00e4chst mit dem Speeboot die Wasserf\u00e4lle von unten begutachtet &#8211; man k\u00f6nnte auch sagen wir haben die Wasserf\u00e4lle aus n\u00e4chster N\u00e4he Hautnah erleben d\u00fcrfen. Danach&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3AlH9-du","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/posts\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":3,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/posts\/836\/revisions"}],"predecessor-version":[{"id":3763,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/posts\/836\/revisions\/3763"}],"wp:attachment":[{"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepponat.de\/blog\/wp-json\/wp\/v2\/tags?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}